{"id":228971,"date":"2026-04-23T02:00:00","date_gmt":"2026-04-23T00:00:00","guid":{"rendered":"https:\/\/staging.fundacioncarf.org\/?p=228971"},"modified":"2026-04-23T11:50:58","modified_gmt":"2026-04-23T09:50:58","slug":"mercadillo-solidario-carf-mochila-vasos-tocados","status":"publish","type":"post","link":"https:\/\/fundacioncarf.org\/it\/mercadillo-solidario-carf-mochila-vasos-tocados\/","title":{"rendered":"Il mercato di beneficenza dei copricapi dei reali che promuove la formazione dei sacerdoti"},"content":{"rendered":"<p>Il recente mercato di beneficenza del <strong>Fondazione CARF<\/strong> ha dimostrato che l'eleganza e l'impegno sociale vanno d'accordo. L'evento, che si \u00e8 tenuto dal 4 al 6 e dall'11 al 13 marzo, la sera dalle 17 alle 20.30, non \u00e8 stato un successo solo tra i benefattori, gli amici e i membri della Fondazione. Il mercatino delle pulci \u00e8 sempre promosso dalla <a href=\"https:\/\/staging.fundacioncarf.org\/voluntariado-patronato-accion-social\/\" data-type=\"page\" data-id=\"214689\" target=\"_blank\" rel=\"noreferrer noopener\">Patronato di Acci\u00f3n Social<\/a>, e divenne una vetrina di raffinatezza grazie agli esclusivi copricapi e alle pamelas della stilista. <strong>Maria Nieto<\/strong> -famoso per aver vestito il <strong>La Regina Letizia<\/strong>,come riportato dall'agenzia Servimedia, le cui creazioni sono state l'attrazione principale dell'evento.<\/p>\n\n\n\n<p>Numerosi <a href=\"https:\/\/staging.fundacioncarf.org\/peregrinaciones-fundacion-carf\/pamplona-encuentro-con-benefactores\/\" target=\"_blank\" data-type=\"page\" data-id=\"200759\" rel=\"noreferrer noopener\">benefattori<\/a> e gli amici della Fondazione si sono riuniti per acquistare tutto, dagli accessori di alta moda ai tesori. <em>vintage<\/em>, trasformando ogni acquisto in un gesto di speranza.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img decoding=\"async\" width=\"1000\" height=\"677\" src=\"https:\/\/staging.fundacioncarf.org\/wp-content\/uploads\/2026\/03\/nieves_herrero.webp\" alt=\"marcadillo solidario fundaci\u00f3n carf mochila vasos sagrados\" class=\"wp-image-228972\" style=\"aspect-ratio:1.4771665659174589;width:795px;height:auto\" srcset=\"https:\/\/fundacioncarf.org\/wp-content\/uploads\/2026\/03\/nieves_herrero.webp 1000w, https:\/\/fundacioncarf.org\/wp-content\/uploads\/2026\/03\/nieves_herrero-300x203.webp 300w, https:\/\/fundacioncarf.org\/wp-content\/uploads\/2026\/03\/nieves_herrero-150x102.webp 150w, https:\/\/fundacioncarf.org\/wp-content\/uploads\/2026\/03\/nieves_herrero-768x520.webp 768w, https:\/\/fundacioncarf.org\/wp-content\/uploads\/2026\/03\/nieves_herrero-18x12.webp 18w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><figcaption class=\"wp-element-caption\">Nieves Herrero durante la sua visita al mercato delle pulci.<\/figcaption><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"nieves-herrero-descubrio-la-mochila-de-vasos-sagrado\">Nieves Herrero al mercatino di beneficenza<\/h2>\n\n\n\n<p>L'evento ha avuto un mecenate d'eccezione: il giornalista <strong>Nieves Herrero<\/strong>. Durante la sua visita, Herrero ha sottolineato l'importanza del lavoro della Fondazione con una frase che riassume lo spirito dell'evento:<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p><em><strong>\u00abLa formazione dei sacerdoti fa bene a tutti\u00bb.<\/strong><\/em><\/p>\n<\/blockquote>\n\n\n\n<p>Uno dei momenti pi\u00f9 toccanti \u00e8 stato quello in cui ha scoperto il <strong>zaino di vasi sacri<\/strong>. Questo kit, al costo di <strong>700 euro<\/strong>, \u00e8 il regalo di laurea pi\u00f9 prezioso per i seminaristi che tornano nelle loro diocesi di origine, sempre in Paesi con scarse risorse economiche. <\/p>\n\n\n\n<p>Lo zaino \u00e8 progettato per consentire loro di celebrare la Santa Messa e di amministrare i sacramenti in piena dignit\u00e0, anche nelle regioni pi\u00f9 remote e con scarse risorse del mondo.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img decoding=\"async\" width=\"940\" height=\"528\" src=\"https:\/\/staging.fundacioncarf.org\/wp-content\/uploads\/2025\/06\/mochila-de-vasos-sagrados-fundacion-carf.webp\" alt=\"Mochila de vasos sagrados de la Fundaci\u00f3n CARF en la que se muestra encima de una mesa todo el contenido de la mochila\" class=\"wp-image-216602\" style=\"aspect-ratio:1.780368260696781;width:787px;height:auto\" srcset=\"https:\/\/fundacioncarf.org\/wp-content\/uploads\/2025\/06\/mochila-de-vasos-sagrados-fundacion-carf.webp 940w, https:\/\/fundacioncarf.org\/wp-content\/uploads\/2025\/06\/mochila-de-vasos-sagrados-fundacion-carf-300x169.webp 300w, https:\/\/fundacioncarf.org\/wp-content\/uploads\/2025\/06\/mochila-de-vasos-sagrados-fundacion-carf-150x84.webp 150w, https:\/\/fundacioncarf.org\/wp-content\/uploads\/2025\/06\/mochila-de-vasos-sagrados-fundacion-carf-768x431.webp 768w, https:\/\/fundacioncarf.org\/wp-content\/uploads\/2025\/06\/mochila-de-vasos-sagrados-fundacion-carf-18x10.webp 18w\" sizes=\"(max-width: 940px) 100vw, 940px\" \/><figcaption class=\"wp-element-caption\">Zaino di vasi sacri della Fondazione CARF.<\/figcaption><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"u\">Lo zaino, un regalo molto apprezzato<\/h3>\n\n\n\n<p>Questo regalo, del valore di 700 euro, \u00e8 considerato uno dei pi\u00f9 apprezzati dai sacerdoti appena ordinati. Contiene tutto il necessario per poter celebrare la Santa Messa e amministrare i sacramenti con dignit\u00e0, anche in luoghi dove i mezzi materiali sono scarsi.<\/p>\n\n\n\n<p><strong>Contenuti dettagliati dello zaino della Fondazione CARF sui biberon:<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Vasi sacri:<\/strong>&nbsp;calice, patena e ciborio per la prenotazione e la distribuzione dell'Eucaristia.<\/li>\n\n\n\n<li><strong>Elementi liturgici:<\/strong>&nbsp;ampolle (vetro trasparente per vino e acqua), croce d'altare e candele.<\/li>\n\n\n\n<li><strong><a href=\"https:\/\/www.google.com\/search?q=Ornamento&amp;rlz=1C1GCCU_esES1161ES1161&amp;oq=contenido+mochila+vasos+sagrados+carf&amp;gs_lcrp=EgZjaHJvbWUyBggAEEUYOTIHCAEQIRigATIHCAIQIRigATIHCAMQIRigATIHCAQQIRigAdIBCTExMTExajBqN6gCALACAA&amp;sourceid=chrome&amp;ie=UTF-8&amp;mstk=AUtExfAFArxDnYBIlYOglCnPos3eaXb95y42QUB9H3ub-bVdx8Waoq-KhkAG_kHQWwK2FUpupsDJ-tcSlBX5-0erSvWiuf5uVgK5csbRVVqSLbpfA9wpqrI3DQNvNlxuQP0Fw5_QA5t1aUXzSHzrQKYic6iZTlcdYkthJJ2zzyK7rCWoERg&amp;csui=3&amp;ved=2ahUKEwiP7dDdxN6TAxUsUKQEHauuGgsQgK4QegQIAxAD\" target=\"_blank\" rel=\"noreferrer noopener\">Ornamento<\/a>:<\/strong>&nbsp;stola (segno di Ges\u00f9 e autorit\u00e0 sacerdotale) dei vari periodi liturgici.<\/li>\n\n\n\n<li><strong>Biancheria da tavola:<\/strong>&nbsp;altare (seta) e altri panni necessari (purificatore, palia).<\/li>\n\n\n\n<li><strong>Aggiuntivo:<\/strong>&nbsp;include i contenitori per l'olio degli infermi e l'aspersione dell'acqua santa.&nbsp;<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"l\">Formazione d'\u00e9lite per un impatto globale<\/h3>\n\n\n\n<p>Questa missione viene portata avanti attraverso prestigiosi centri accademici dove vengono formati coloro che, in futuro, porteranno il loro lavoro pastorale negli angoli pi\u00f9 bisognosi del mondo.<\/p>\n\n\n\n<p>Al di l\u00e0 della moda, l'obiettivo di questo mercatino delle pulci \u00e8 quello di raccogliere fondi per l'associazione <strong>formazione completa<\/strong> (umano, intellettuale e spirituale) di sacerdoti e religiosi. I beneficiari studiano in centri come:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Universit\u00e0 di Navarra<\/strong> (Spagna).<\/li>\n\n\n\n<li><strong>Pontificia Universit\u00e0 della Santa Croce<\/strong> (Roma).<\/li>\n<\/ul>\n\n\n\n<p>Una giornata in cui la moda \u00e8 diventata un veicolo di speranza, e in cui ogni acquisto \u00e8 stato anche un gesto di sostegno per una causa che trascende i confini.<\/p>\n\n\n\n<p>Grazie alla generosit\u00e0 dei partecipanti, questi futuri pastori potranno portare il loro lavoro negli angoli pi\u00f9 bisognosi del mondo, con una preparazione accademica e spirituale di prima classe.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"objetos-liturgicos-de-la-mochila\">Oggetti liturgici nella borsa dei vasi sacri<\/h4>\n\n\n\n<p><\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Servire la Chiesa: oggetti e paramenti liturgici 2\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/RMf7z2-QDbU?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<p><strong>Jos\u00e9 Luis Sol\u00eds,&nbsp;<\/strong>sacerdote della diocesi messicana di Celaya, ricorda quando \u00abalcuni parroci mi chiesero di aiutarli a celebrare l'Eucaristia in luoghi remoti delle loro parrocchie\u00bb. \u00abPer raggiungere questi luoghi, il cui paesaggio era bellissimo e dove c'era un grande silenzio, a volte era necessario salire su un cavallo e andare in chiesa.&nbsp;<strong>a cavallo o su un asino<\/strong>&nbsp;o continuare a camminare per raggiungere il luogo e poter celebrare la Messa\u00bb, continua. Una volta l\u00ec, il sacerdote ha aperto il suo zaino, ne ha dispiegato il contenuto e ha iniziato l'Eucaristia, alla quale hanno partecipato fedeli provenienti da tutti i villaggi circostanti. \u00abRingrazio la fondazione e prego Dio per i frutti di questo lavoro\u00bb, conclude.<\/p>\n\n\n\n<p id=\"ropa-de-ceremonia-y-complementos\"><strong>Abiti e accessori da cerimonia<\/strong><\/p>\n\n\n\n<p>Inoltre, il mercatino delle pulci offriva anche abiti e accessori da cerimonia e di uso quotidiano, in un'atmosfera di generosit\u00e0 e cordialit\u00e0. I fondi raccolti saranno destinati all'attivit\u00e0 della Fondazione CARF per la <a href=\"https:\/\/staging.fundacioncarf.org\/conoce-fundacion-carf\/\" target=\"_blank\" data-type=\"link\" data-id=\"https:\/\/staging.fundacioncarf.org\/conoce-fundacion-carf\/\" rel=\"noreferrer noopener\">formazione completa<\/a> -Lo sviluppo intellettuale, umano e spirituale dei sacerdoti diocesani, dei seminaristi e dei religiosi e delle religiose di tutto il mondo.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<div class=\"wp-block-rank-math-toc-block\" id=\"rank-math-toc\"><p><strong>Indice dei contenuti<\/strong><\/p><nav><ul><li class=\"\"><a href=\"#nieves-herrero-descubrio-la-mochila-de-vasos-sagrado\">Nieves Herrero al mercatino di beneficenza<\/a><ul><li class=\"\"><a href=\"#u\">Lo zaino, un regalo molto apprezzato<\/a><\/li><li class=\"\"><a href=\"#l\">Formazione d'\u00e9lite per un impatto globale<\/a><\/li><\/ul><\/li><\/ul><\/nav><\/div>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<p><strong>Marta Sant\u00edn<\/strong>giornalista specializzata in religione. <\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"TESTIMONIANZE : Storie di sacerdoti\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/AI3Ibzei3_A?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>","protected":false},"excerpt":{"rendered":"<p>Il Consiglio di Azione Sociale della Fondazione CARF ha organizzato un mercatino di moda di beneficenza a Madrid con pezzi esclusivi della stilista Mar\u00eda Nieto. L'evento ha visto la partecipazione di Nieves Herrero e ha sensibilizzato l'opinione pubblica su iniziative come lo zaino dei vasi sacri. I fondi raccolti sostengono la formazione integrale dei sacerdoti in tutto il mondo.<\/p>","protected":false},"author":4,"featured_media":228974,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"give_campaign_id":0,"footnotes":""},"categories":[13],"tags":[207,381],"class_list":["post-228971","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog","tag-mercadillo-solidario","tag-mochila-de-vasos-sagrados"],"acf":[],"_links":{"self":[{"href":"https:\/\/fundacioncarf.org\/it\/wp-json\/wp\/v2\/posts\/228971","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fundacioncarf.org\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fundacioncarf.org\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fundacioncarf.org\/it\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/fundacioncarf.org\/it\/wp-json\/wp\/v2\/comments?post=228971"}],"version-history":[{"count":12,"href":"https:\/\/fundacioncarf.org\/it\/wp-json\/wp\/v2\/posts\/228971\/revisions"}],"predecessor-version":[{"id":229581,"href":"https:\/\/fundacioncarf.org\/it\/wp-json\/wp\/v2\/posts\/228971\/revisions\/229581"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fundacioncarf.org\/it\/wp-json\/wp\/v2\/media\/228974"}],"wp:attachment":[{"href":"https:\/\/fundacioncarf.org\/it\/wp-json\/wp\/v2\/media?parent=228971"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fundacioncarf.org\/it\/wp-json\/wp\/v2\/categories?post=228971"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fundacioncarf.org\/it\/wp-json\/wp\/v2\/tags?post=228971"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}