{"id":181703,"date":"2023-05-15T20:57:19","date_gmt":"2023-05-15T18:57:19","guid":{"rendered":"https:\/\/staging.fundacioncarf.org\/colabora\/pon-cara-a-tu-donativo\/elvin-octavio-espinoza-mora\/"},"modified":"2025-07-23T11:55:02","modified_gmt":"2025-07-23T09:55:02","slug":"elvin-octavio-espinoza-mora","status":"publish","type":"candidatos","link":"https:\/\/fundacioncarf.org\/it\/colabora\/pon-cara-a-tu-donativo\/elvin-octavio-espinoza-mora\/","title":{"rendered":"Elvin Octavio Espinoza Mora"},"content":{"rendered":"<p><span style=\"font-weight: 400;\">\"<\/span>Grazie alle vostre preghiere, sto avanzando nella mia ricerca di diventare un altro Cristo. Allo stesso modo, cos\u00ec come aiutate spiritualmente, aiutate anche materialmente, perch\u00e9 questo non sarebbe possibile senza persone dal cuore generoso, che pensano al futuro della Chiesa. Per questo motivo la ringrazio incondizionatamente per il suo carisma di servizio, collaborazione e disponibilit\u00e0.<\/p>\n<p>Dio benedica il lavoro che svolge nella Chiesa, affinch\u00e9 sia fruttuoso, e benedica il suo lavoro personale. Perch\u00e9 questa \u00e8 la causa da cui nasceranno pi\u00f9 atti di generosit\u00e0 nel mondo, pi\u00f9 sacerdoti nella Chiesa e pi\u00f9 persone dedicate dal suo esempio. La affido a nostra Madre, la Vergine Maria, figlia di Dio Padre, Madre di Dio Figlio e Sposa di Dio Spirito Santo.<span style=\"font-weight: 400;\">\"<\/span>.<\/p>","protected":false},"excerpt":{"rendered":"<p>\u00abGracias a sus oraciones sigo adelante en busca de ser otro Cristo. Del mismo modo, as\u00ed como ayudan en lo espiritual, lo hacen tambi\u00e9n en lo material, porque esto no se lograr\u00eda sin las personas de coraz\u00f3n generoso, que piensan en el futuro de la Iglesia. Por este motivo me dirijo a ustedes agradeci\u00e9ndoles, de [&hellip;]<\/p>\n","protected":false},"featured_media":0,"menu_order":0,"template":"","format":"standard","meta":{"_acf_changed":false,"give_campaign_id":0,"footnotes":""},"tags":[120],"pcatd":[],"cantidad":[],"continente":[],"estadobeca":[3],"class_list":["post-181703","candidatos","type-candidatos","status-publish","format-standard","hentry","tag-sacerdote","estadobeca-en-curso"],"acf":[],"_links":{"self":[{"href":"https:\/\/fundacioncarf.org\/it\/wp-json\/wp\/v2\/candidatos\/181703","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fundacioncarf.org\/it\/wp-json\/wp\/v2\/candidatos"}],"about":[{"href":"https:\/\/fundacioncarf.org\/it\/wp-json\/wp\/v2\/types\/candidatos"}],"version-history":[{"count":1,"href":"https:\/\/fundacioncarf.org\/it\/wp-json\/wp\/v2\/candidatos\/181703\/revisions"}],"predecessor-version":[{"id":219038,"href":"https:\/\/fundacioncarf.org\/it\/wp-json\/wp\/v2\/candidatos\/181703\/revisions\/219038"}],"wp:attachment":[{"href":"https:\/\/fundacioncarf.org\/it\/wp-json\/wp\/v2\/media?parent=181703"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fundacioncarf.org\/it\/wp-json\/wp\/v2\/tags?post=181703"},{"taxonomy":"pcatd","embeddable":true,"href":"https:\/\/fundacioncarf.org\/it\/wp-json\/wp\/v2\/pcatd?post=181703"},{"taxonomy":"cantidad","embeddable":true,"href":"https:\/\/fundacioncarf.org\/it\/wp-json\/wp\/v2\/cantidad?post=181703"},{"taxonomy":"continente","embeddable":true,"href":"https:\/\/fundacioncarf.org\/it\/wp-json\/wp\/v2\/continente?post=181703"},{"taxonomy":"estadobeca","embeddable":true,"href":"https:\/\/fundacioncarf.org\/it\/wp-json\/wp\/v2\/estadobeca?post=181703"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}