{"id":229271,"date":"2026-04-25T02:00:00","date_gmt":"2026-04-25T00:00:00","guid":{"rendered":"https:\/\/fundacioncarf.org\/?p=229271"},"modified":"2026-04-17T13:24:08","modified_gmt":"2026-04-17T11:24:08","slug":"san-marcos-evangelista-festividad-25-abril","status":"publish","type":"post","link":"https:\/\/fundacioncarf.org\/fr\/san-marcos-evangelista-festividad-25-abril\/","title":{"rendered":"25 avril, Saint Marc l'\u00e9vang\u00e9liste : vie et \u00e9vangile"},"content":{"rendered":"<p class=\"wp-block-paragraph\">Chaque <strong>25 avril<\/strong>, l'\u00c9glise catholique s'habille pour c\u00e9l\u00e9brer la f\u00eate du <strong>St Mark's<\/strong>, l'un des quatre \u00e9vang\u00e9listes qui, inspir\u00e9s par l'Esprit Saint, ont mis par \u00e9crit la vie, la passion, la mort et la r\u00e9surrection de Notre Seigneur J\u00e9sus-Christ. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La figure de saint Marc est essentielle pour comprendre l'essence de notre foi. Son \u00c9vangile, consid\u00e9r\u00e9 par les sp\u00e9cialistes comme le plus ancien des quatre \u00c9vangiles, est un r\u00e9cit vivant, direct et plein d'action qui nous invite \u00e0 d\u00e9couvrir l'identit\u00e9 de J\u00e9sus en tant que Fils de Dieu.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dans cet article, nous voulons aborder la vie de ce saint primitif, explorer les caract\u00e9ristiques de son texte sacr\u00e9 \u00e0 la lumi\u00e8re de l'histoire de l'humanit\u00e9. <a href=\"https:\/\/www.vatican.va\/content\/vatican\/es.html\" data-type=\"link\" data-id=\"https:\/\/www.vatican.va\/content\/vatican\/es.html\" target=\"_blank\" rel=\"noreferrer noopener\">Magist\u00e8re de l'\u00c9glise<\/a> et les enseignements de <a href=\"https:\/\/fundacioncarf.org\/san-josemaria-escriva-fiesta-liturgica\/\" data-type=\"link\" data-id=\"https:\/\/fundacioncarf.org\/san-josemaria-escriva-fiesta-liturgica\/\">Saint Jos\u00e9maria<\/a>. Nous r\u00e9fl\u00e9chirons \u00e0 la mani\u00e8re dont sa figure est aujourd'hui \u00e0 l'origine de l'initiative de l'Union europ\u00e9enne. <a href=\"https:\/\/fundacioncarf.org\/sacerdocio\/formacion-de-sacerdotes\/\" data-type=\"link\" data-id=\"https:\/\/fundacioncarf.org\/sacerdocio\/formacion-de-sacerdotes\/\" target=\"_blank\" rel=\"noreferrer noopener\">formation des pr\u00eatres<\/a> dans le monde entier.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Qui \u00e9tait saint Marc ? Auteur, datation et destinataires du 2e \u00e9vangile\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/H5ZmQE4Ywks?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"quien-fue-verdaderamente-san-marcos\">Qui \u00e9tait Saint Marc ?<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Rencontrer <strong>St Mark's<\/strong>, Dans les premiers temps de la <a href=\"https:\/\/fundacioncarf.org\/san-gregorio-magno-papa-santo-historia-legado\/\" data-type=\"link\" data-id=\"https:\/\/fundacioncarf.org\/san-gregorio-magno-papa-santo-historia-legado\/\" target=\"_blank\" rel=\"noreferrer noopener\">Histoire de l'\u00c9glise<\/a>, comme en t\u00e9moignent les Actes des Ap\u00f4tres et certaines lettres du Nouveau Testament. Connu \u00e9galement sous le nom de Jean Marc, il ne faisait pas partie du groupe des douze ap\u00f4tres, mais sa vie \u00e9tait li\u00e9e aux deux piliers de l'\u00c9glise : saint Pierre et saint Paul.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La tradition de l'\u00c9glise nous place dans <a href=\"https:\/\/fundacioncarf.org\/peregrinaciones-fundacion-carf\/tierra-santa-peregrina\/\" data-type=\"page\" data-id=\"170107\" target=\"_blank\" rel=\"noreferrer noopener\">J\u00e9rusalem<\/a>. La m\u00e8re de Marc, Marie, \u00e9tait une femme ais\u00e9e de la premi\u00e8re communaut\u00e9 chr\u00e9tienne, et sa maison servait de lieu de rencontre pour les premiers fid\u00e8les. Il est tr\u00e8s probable que la derni\u00e8re C\u00e8ne ait eu lieu dans cette maison et que les disciples s'y soient r\u00e9fugi\u00e9s, effray\u00e9s, apr\u00e8s l'assassinat du Christ. <a href=\"https:\/\/fundacioncarf.org\/jesucristo-esperanza-catequesis-papa-leon-xiv\/\" data-type=\"link\" data-id=\"https:\/\/fundacioncarf.org\/jesucristo-esperanza-catequesis-papa-leon-xiv\/\" target=\"_blank\" rel=\"noreferrer noopener\">crucifixion<\/a>. Puis ils se r\u00e9unissaient l\u00e0, unis dans l'attente de la venue de l'Esprit Saint en <a href=\"https:\/\/fundacioncarf.org\/pentecostes-llegada-de-un-amigo\/\" data-type=\"link\" data-id=\"https:\/\/fundacioncarf.org\/pentecostes-llegada-de-un-amigo\/\" target=\"_blank\" rel=\"noreferrer noopener\">Pentec\u00f4te<\/a>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Compagnon de route de Paul et Barnab\u00e9<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dans les premiers temps de la propagation du christianisme, <strong>St Mark's<\/strong> accompagna son cousin, saint Barnab\u00e9, et saint Paul lors du premier voyage missionnaire \u00e0 Chypre. Bien que Marc ait d\u00e9cid\u00e9 de retourner \u00e0 J\u00e9rusalem - un \u00e9pisode qui a provoqu\u00e9 quelques frictions et de la col\u00e8re de la part de saint Paul - la gr\u00e2ce de Dieu a permis une r\u00e9conciliation. Des ann\u00e9es plus tard, nous voyons un Marc m\u00fbr accompagner \u00e0 nouveau Paul pendant sa captivit\u00e9 \u00e0 Rome.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>L\"\"interpr\u00e8te\" de saint Pierre<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mais le lien le plus profond dans <strong>St Mark's<\/strong> \u00e9tait avec l'ap\u00f4tre Pierre. Le premier pape l'appelle affectueusement \"mon fils Marc\" dans sa premi\u00e8re lettre (1 Pierre 5, 13). La tradition unanime de l'\u00c9glise, qui est consign\u00e9e dans les documents de la <a href=\"https:\/\/fundacioncarf.org\/la-basilica-de-san-pedro-cumple-400-anos-de-vida\/\" data-type=\"link\" data-id=\"https:\/\/fundacioncarf.org\/la-basilica-de-san-pedro-cumple-400-anos-de-vida\/\" target=\"_blank\" rel=\"noreferrer noopener\">Saint-Si\u00e8ge<\/a> et dans les \u00e9crits des P\u00e8res de l'\u00c9glise comme Papias de Hi\u00e9rapolis et saint Ir\u00e9n\u00e9e, confirme que Marc a \u00e9t\u00e9 l'interpr\u00e8te de Pierre. Son \u00c9vangile n'est rien d'autre que le r\u00e9cit \u00e9crit de l'histoire de Pierre. <a href=\"https:\/\/fundacioncarf.org\/jesucristo-esperanza-catequesis-papa-leon-xiv\/\" data-type=\"link\" data-id=\"https:\/\/fundacioncarf.org\/jesucristo-esperanza-catequesis-papa-leon-xiv\/\" target=\"_blank\" rel=\"noreferrer noopener\">la cat\u00e9ch\u00e8se orale<\/a> et la pr\u00e9dication de <a href=\"https:\/\/fundacioncarf.org\/solemnidad-san-pedro-y-san-pablo-29-de-junio\/\" data-type=\"link\" data-id=\"https:\/\/fundacioncarf.org\/solemnidad-san-pedro-y-san-pablo-29-de-junio\/\">St. Peter's<\/a> aux chr\u00e9tiens de <a href=\"https:\/\/fundacioncarf.org\/peregrinaciones-fundacion-carf\/peregrina-carf-roma\/\" data-type=\"link\" data-id=\"https:\/\/fundacioncarf.org\/peregrinaciones-fundacion-carf\/peregrina-carf-roma\/\" target=\"_blank\" rel=\"noreferrer noopener\">Roma<\/a>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cette proximit\u00e9 avec la source originale et primaire signifie que lire saint Marc, c'est essentiellement \u00e9couter la voix vivante de saint Pierre qui rappelle les gestes, les regards et les miracles de saint Pierre. <a href=\"https:\/\/fundacioncarf.org\/libro-jesus-de-nazaret-historia-gerardo-ferrara\/\" data-type=\"link\" data-id=\"https:\/\/fundacioncarf.org\/libro-jesus-de-nazaret-historia-gerardo-ferrara\/\" target=\"_blank\" rel=\"noreferrer noopener\">J\u00e9sus de Nazareth<\/a>.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"el-evangelio-segun-san-marcos-caracteristicas-y-mensaje\">Quelles sont les caract\u00e9ristiques de l'\u00c9vangile selon Marc ?<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">L'histoire qu'il nous raconte <strong>St Mark's<\/strong> est le plus court des quatre \u00c9vangiles (16 chapitres), mais ce qu'il manque en longueur, il le compense en intensit\u00e9. Il s'agit d'un <a href=\"https:\/\/fundacioncarf.org\/sacerdote-ecuador-franscisco-sojos\/\" data-type=\"link\" data-id=\"https:\/\/fundacioncarf.org\/sacerdote-ecuador-franscisco-sojos\/\" target=\"_blank\" rel=\"noreferrer noopener\">\u00c9vangile<\/a> \u00e9crit principalement pour les chr\u00e9tiens issus du paganisme, en particulier de Rome. C'est pourquoi il omet les longues g\u00e9n\u00e9alogies ou les explications exhaustives des lois juives, se concentrant davantage sur l'action.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\" id=\"un-relato-vivo-directo-y-urgente\"><strong>Un r\u00e9cit vivant, direct et urgent<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">L'un des mots les plus fr\u00e9quemment r\u00e9p\u00e9t\u00e9s dans le texte grec original est le suivant <em>euthys<\/em>, qui signifie \"imm\u00e9diatement\" ou \"tout de suite\". L'\u00c9vangile avance \u00e0 grands pas. <a href=\"https:\/\/fundacioncarf.org\/la-figura-historica-de-jesus-de-nazaret\/\" target=\"_blank\" data-type=\"link\" data-id=\"https:\/\/fundacioncarf.org\/la-figura-historica-de-jesus-de-nazaret\/\" rel=\"noreferrer noopener\">J\u00e9sus-Christ<\/a> Il gu\u00e9rit, pr\u00eache, chasse les d\u00e9mons, marche sur les eaux et se dirige r\u00e9solument vers J\u00e9rusalem pour consommer son sacrifice en <a href=\"https:\/\/fundacioncarf.org\/la-cruz-el-espiritu-santo-y-la-iglesia\/\" target=\"_blank\" data-type=\"link\" data-id=\"https:\/\/fundacioncarf.org\/la-cruz-el-espiritu-santo-y-la-iglesia\/\" rel=\"noreferrer noopener\">la Croix<\/a>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>San Marcos<\/strong> veut que le lecteur se pose une question fondamentale d\u00e8s le premier verset : <em>\"Qui est cet homme ?\"<\/em>. Par ce que les th\u00e9ologiens ont appel\u00e9 le secret messianique, J\u00e9sus demande souvent \u00e0 ceux qu'il gu\u00e9rit ou aux d\u00e9mons eux-m\u00eames de ne pas r\u00e9v\u00e9ler son identit\u00e9. Pourquoi ? Parce que J\u00e9sus ne veut pas \u00eatre pris pour un leader politique ou un messie terrestre. Sa v\u00e9ritable identit\u00e9 de Fils de Dieu n'est pleinement comprise qu'au pied de la Croix. En fait, c'est un centurion romain (un pa\u00efen) qui est le premier \u00e0 la confesser apr\u00e8s sa mort : <em>\"Cet homme \u00e9tait vraiment le Fils de Dieu\".\"<\/em> (Mc 15, 39).<\/p>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img decoding=\"async\" width=\"1000\" height=\"667\" src=\"https:\/\/fundacioncarf.org\/wp-content\/uploads\/2026\/04\/evangelio_san_marcos.webp\" alt=\"san marcos evangelista evangelio\" class=\"wp-image-229275\" style=\"aspect-ratio:1.4992888417882142;width:793px;height:auto\" srcset=\"https:\/\/fundacioncarf.org\/wp-content\/uploads\/2026\/04\/evangelio_san_marcos.webp 1000w, https:\/\/fundacioncarf.org\/wp-content\/uploads\/2026\/04\/evangelio_san_marcos-300x200.webp 300w, https:\/\/fundacioncarf.org\/wp-content\/uploads\/2026\/04\/evangelio_san_marcos-150x100.webp 150w, https:\/\/fundacioncarf.org\/wp-content\/uploads\/2026\/04\/evangelio_san_marcos-768x512.webp 768w, https:\/\/fundacioncarf.org\/wp-content\/uploads\/2026\/04\/evangelio_san_marcos-18x12.webp 18w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\" id=\"la-humanidad-de-cristo\"><strong>L'humanit\u00e9 du Christ<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Un autre aspect poignant du travail de <strong>St Mark's<\/strong> est la mani\u00e8re dont il d\u00e9taille l'humanit\u00e9 de J\u00e9sus. Il d\u00e9crit un Christ qui a compassion de la foule (Mc 6,34), qui s'indigne de la duret\u00e9 du c\u0153ur (Mc 3,5), qui embrasse et b\u00e9nit les enfants (Mc 10,16), qui \u00e9prouve de la crainte et de l'angoisse dans le jardin de Geths\u00e9mani (Mc 14,33). Cette approche tr\u00e8s humaine et tr\u00e8s divine est une source in\u00e9puisable d'inspiration pour l'\u00c9glise. <a href=\"https:\/\/fundacioncarf.org\/la-oracion-escuela-de-misericordia\/\" data-type=\"link\" data-id=\"https:\/\/fundacioncarf.org\/la-oracion-escuela-de-misericordia\/\" target=\"_blank\" rel=\"noreferrer noopener\">la pri\u00e8re<\/a> le personnel.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\" id=\"la-ensenanza-de-san-josemaria-y-la-vida-en-el-evangelio\"><strong>L'enseignement de saint Jos\u00e9maria : vivre l'\u00c9vangile<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La sensibilit\u00e9 propos\u00e9e par la <strong>Fondation CARF<\/strong>, inspir\u00e9 par la formation sacerdotale et les enseignements de <a href=\"https:\/\/fundacioncarf.org\/san-josemaria-escriva-de-balaguer\/\" data-type=\"link\" data-id=\"https:\/\/fundacioncarf.org\/san-josemaria-escriva-de-balaguer\/\" target=\"_blank\" rel=\"noreferrer noopener\">Saint Jos\u00e9maria Escriva<\/a> (fondateur de l'Opus Dei), conna\u00eetre et vivre la Parole de Dieu est vital.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Saint Jos\u00e9maria a recommand\u00e9 avec insistance la <a href=\"https:\/\/fundacioncarf.org\/oracion-en-familia-como-aprender-a-orar\/\" data-type=\"link\" data-id=\"https:\/\/fundacioncarf.org\/oracion-en-familia-como-aprender-a-orar\/\" target=\"_blank\" rel=\"noreferrer noopener\">lecture et m\u00e9ditation<\/a> du Saint \u00c9vangile. Dans son \u0153uvre, nous sommes invit\u00e9s non seulement \u00e0 lire les pages sacr\u00e9es comme on lit un livre d'histoire ancienne, mais \u00e0 les vivre. Comme il l'a souvent enseign\u00e9 : \u00abJe vous conseille, dans votre pri\u00e8re, d'intervenir dans les passages de l'\u00c9vangile, comme l'un des personnages (Amis de Dieu, point 253)\u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Lisez l'\u00c9vangile de <strong>St Mark's<\/strong> Dans cette lumi\u00e8re, notre perspective change compl\u00e8tement. Nous faisons partie de la foule qui presse J\u00e9sus au bord du lac de G\u00e9n\u00e9sareth, nous sommes l'aveugle Bartim\u00e9e qui, du bord de la route, crie mis\u00e9ricorde, ou ces ap\u00f4tres qui, au milieu de la temp\u00eate en mer, r\u00e9veillent le Ma\u00eetre avec une grande peur et une foi vacillante. \u00c0 travers les \u00e9crits de saint Jos\u00e9maria, nous voyons que cette familiarit\u00e9 avec la vie du Christ est un soutien pour comprendre et vivre la vie de l'\u00c9glise. <a href=\"https:\/\/fundacioncarf.org\/padre-pio-sacerdote-ejemplo-profundo-de-santidad\/\" data-type=\"link\" data-id=\"https:\/\/fundacioncarf.org\/padre-pio-sacerdote-ejemplo-profundo-de-santidad\/\" target=\"_blank\" rel=\"noreferrer noopener\">la saintet\u00e9 au milieu du monde<\/a>. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Saint Marc, en reprenant la cat\u00e9ch\u00e8se de Pierre, nous a donn\u00e9 un manuel pratique pour rencontrer J\u00e9sus-Christ dans notre vie quotidienne, dans nos occupations quotidiennes, nous invitant \u00e0 \u00eatre porteurs de son message dans nos propres familles et sur nos lieux de travail.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"la-celebracion-del-25-de-abril-y-la-tradicion-eclesial\">C\u00e9l\u00e9bration du 25 avril et tradition <\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Le site <strong>25 avril<\/strong>, la liturgie de la <a href=\"https:\/\/fundacioncarf.org\/herencias-y-legados-solidarios-que-construyen-fe\/\" data-type=\"link\" data-id=\"https:\/\/fundacioncarf.org\/herencias-y-legados-solidarios-que-construyen-fe\/\" target=\"_blank\" rel=\"noreferrer noopener\">\u00c9glise universelle<\/a> nous appelle \u00e0 c\u00e9l\u00e9brer la f\u00eate de <strong>St Mark's<\/strong>. C'est un jour de joie qui, en plus de rendre hommage \u00e0 la <a href=\"https:\/\/fundacioncarf.org\/san-mateo-apostol-como-evangelizar-siglo-xxi\/\" data-type=\"link\" data-id=\"https:\/\/fundacioncarf.org\/san-mateo-apostol-como-evangelizar-siglo-xxi\/\" target=\"_blank\" rel=\"noreferrer noopener\">\u00e9vang\u00e9liste<\/a>, Les textes liturgiques approuv\u00e9s par le Saint-Si\u00e8ge et promus par la Conf\u00e9rence \u00e9piscopale espagnole pour cette journ\u00e9e soulignent l'importance de la transmission de la foi. Les textes liturgiques approuv\u00e9s par le Saint-Si\u00e8ge et promus par la Conf\u00e9rence \u00e9piscopale espagnole pour cette journ\u00e9e soulignent la responsabilit\u00e9 apostolique que partagent tous les baptis\u00e9s.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dans la liturgie des heures, l'\u00c9glise prie Dieu pour que, de m\u00eame qu'il a donn\u00e9 \u00e0 saint Marc la gr\u00e2ce de pr\u00eacher l'\u00c9vangile, nous puissions nous aussi profiter de ses enseignements pour suivre fid\u00e8lement les traces du Christ. C'est un jour propice pour <a href=\"https:\/\/fundacioncarf.org\/cuaresma-perdon-dios-conversion-cristiana\/\" data-type=\"link\" data-id=\"https:\/\/fundacioncarf.org\/cuaresma-perdon-dios-conversion-cristiana\/\" target=\"_blank\" rel=\"noreferrer noopener\">renouveler notre amour<\/a> par les Saintes \u00c9critures. Comme nous l'a rappel\u00e9 le pape Fran\u00e7ois, garder un petit \u00e9vangile dans sa poche et en lire un extrait chaque jour est une pratique spirituelle fortement recommand\u00e9e pour se laisser transformer par le regard du Christ.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\" id=\"el-leon-alado-simbolo-de-san-marcos\"><strong>Le lion ail\u00e9 : symbole de Saint-Marc<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Lorsque l'on parle de ce saint, il faut mentionner sa repr\u00e9sentation iconographique : le <strong>lion ail\u00e9<\/strong>. Cette image, profond\u00e9ment enracin\u00e9e dans l'histoire de l'art chr\u00e9tien et inspir\u00e9e des visions du proph\u00e8te Ez\u00e9chiel et du livre de l'Apocalypse, a une pr\u00e9cieuse signification th\u00e9ologique.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La tradition chr\u00e9tienne, en particulier celle des <strong>Saint J\u00e9r\u00f4me<\/strong> (IVe si\u00e8cle), a attribu\u00e9 le lion \u00e0 saint Marc, parce que son \u00c9vangile commence par la figure de saint Jean-Baptiste criant dans le d\u00e9sert. \u00abLa voix de celui qui crie dans le d\u00e9sert : Pr\u00e9parez le chemin du Seigneur, aplanissez ses sentiers\u00bb (Mc 1,3). Les anciens ex\u00e9g\u00e8tes associaient cette voix puissante et solitaire dans la steppe au rugissement du lion, roi de la for\u00eat et du d\u00e9sert.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dans le bestiaire m\u00e9di\u00e9val et l'ex\u00e9g\u00e8se patristique, on croyait que les lionceaux naissaient morts et que leur p\u00e8re les ramenait \u00e0 la vie en rugissant le troisi\u00e8me jour. C'est devenu un symbole parfait pour l'\u00c9vangile de Marc, qui souligne avec force la majest\u00e9 et la victoire du Christ (le Lion de Juda) sur la mort gr\u00e2ce \u00e0 sa glorieuse r\u00e9surrection.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Les ailes qui accompagnent le lion repr\u00e9sentent les <strong>la nature divine et l'inspiration c\u00e9leste<\/strong> des \u00e9crits sacr\u00e9s. Elles indiquent que le message de l'\u00e9vang\u00e9liste n'est pas purement humain, mais qu'il vient d'en haut, reliant la terre \u00e0 la divinit\u00e9.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cette iconographie orne des milliers d'\u00e9glises dans le monde, la plus c\u00e9l\u00e8bre \u00e9tant la basilique Saint-Marc de Venise, ville dont il est le patron incontest\u00e9 et o\u00f9 reposent ses reliques.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"402\" src=\"https:\/\/fundacioncarf.org\/wp-content\/uploads\/2026\/01\/sacerdotes-vaticano-fundacion-carf-1024x402.webp\" alt=\"\" class=\"wp-image-227587\" srcset=\"https:\/\/fundacioncarf.org\/wp-content\/uploads\/2026\/01\/sacerdotes-vaticano-fundacion-carf-1024x402.webp 1024w, https:\/\/fundacioncarf.org\/wp-content\/uploads\/2026\/01\/sacerdotes-vaticano-fundacion-carf-300x118.webp 300w, https:\/\/fundacioncarf.org\/wp-content\/uploads\/2026\/01\/sacerdotes-vaticano-fundacion-carf-150x59.webp 150w, https:\/\/fundacioncarf.org\/wp-content\/uploads\/2026\/01\/sacerdotes-vaticano-fundacion-carf-768x302.webp 768w, https:\/\/fundacioncarf.org\/wp-content\/uploads\/2026\/01\/sacerdotes-vaticano-fundacion-carf-18x7.webp 18w, https:\/\/fundacioncarf.org\/wp-content\/uploads\/2026\/01\/sacerdotes-vaticano-fundacion-carf.webp 1400w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\" id=\"la-mision-de-la-fundacion-carf-llevar-el-evangelio-al-mundo-entero\"><strong>Objectif de la Fondation CARF : apporter l'Evangile au monde entier<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">L'ouvrage r\u00e9dig\u00e9 par <strong>St Mark's<\/strong> se termine par le grand commandement missionnaire de J\u00e9sus : \u00abAllez dans le monde entier et proclamez l'\u00c9vangile \u00e0 toute la cr\u00e9ation\u00bb (Mc 16, 15). Ce verset n'est pas seulement une brillante conclusion de son livre ; il est le battement de c\u0153ur permanent de l'\u00c9glise et constitue, d'une mani\u00e8re tr\u00e8s directe, l'une des raisons d'\u00eatre de l'\u00c9glise catholique. <strong><a href=\"https:\/\/fundacioncarf.org\/conoce-fundacion-carf\/\" data-type=\"link\" data-id=\"https:\/\/fundacioncarf.org\/conoce-fundacion-carf\/\" target=\"_blank\" rel=\"noreferrer noopener\">Fondation CARF<\/a><\/strong> (Centro Acad\u00e9mico Romano Fundaci\u00f3n).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pour que l'\u00c9vangile \u00e9crit par saint Marc continue \u00e0 r\u00e9sonner puissamment aujourd'hui, pour qu'il continue \u00e0 toucher les c\u0153urs dans les grandes villes d\u00e9christianis\u00e9es et dans les missions les plus \u00e9loign\u00e9es et les pays les plus abandonn\u00e9s et les plus pauvres, l'\u00c9glise doit <a href=\"https:\/\/fundacioncarf.org\/sacerdocio\/\" data-type=\"link\" data-id=\"https:\/\/fundacioncarf.org\/sacerdocio\/\" target=\"_blank\" rel=\"noreferrer noopener\">les saints pr\u00eatres<\/a>, Elle a besoin de bergers bien form\u00e9s, sages et ayant l'odeur des brebis. Elle a besoin d'hommes qui, comme Marc lui-m\u00eame l'a fait avec saint Pierre, s'assoient aux pieds de la sagesse de l'\u00c9glise et portent ensuite cette v\u00e9rit\u00e9 de mani\u00e8re accessible et passionn\u00e9e aux quatre coins du monde.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La Fondation CARF travaille sans rel\u00e2che pour soutenir la formation solide et int\u00e9grale des s\u00e9minaristes, <a href=\"https:\/\/fundacioncarf.org\/sacerdocio\/vocacion-sacerdotal\/\" data-type=\"link\" data-id=\"https:\/\/fundacioncarf.org\/sacerdocio\/vocacion-sacerdotal\/\" target=\"_blank\" rel=\"noreferrer noopener\">pr\u00eatres dioc\u00e9sains<\/a>, Nous contribuons \u00e9galement \u00e0 r\u00e9unir des religieux et religieuses du monde entier, en particulier dans les r\u00e9gions o\u00f9 l'\u00c9glise est pers\u00e9cut\u00e9e ou manque de ressources. En leur permettant d'\u00e9tudier \u00e0 l'Universit\u00e9 pontificale de la Sainte-Croix \u00e0 Rome ou aux Facult\u00e9s eccl\u00e9siastiques de l'Universit\u00e9 de Navarre \u00e0 Pampelune, nous investissons directement dans la diffusion de la Parole de Dieu.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Un pr\u00eatre bien form\u00e9 en th\u00e9ologie biblique, qui comprend les profondeurs litt\u00e9raires, historiques et spirituelles de l'\u00c9vangile de J\u00e9sus-Christ, est un pr\u00eatre de l'\u00c9glise. <strong>St Mark's<\/strong>, C'est un pr\u00eatre capable de soutenir la foi de milliers d'\u00e2mes. Comme la m\u00e8re de Marc, il met sa maison \u00e0 la disposition des Ap\u00f4tres, <a href=\"https:\/\/fundacioncarf.org\/donar\/\" data-type=\"page\" data-id=\"170000\" target=\"_blank\" rel=\"noreferrer noopener\">les bienfaiteurs de la Fondation CARF ont mis \u00e0 disposition leurs ressources<\/a> \u00e0 la disposition des futurs pasteurs de l'\u00c9glise dioc\u00e9saine.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\" id=\"la-vigencia-de-un-mensaje-eterno\"><strong>La validit\u00e9 d'un message intemporel<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En c\u00e9l\u00e9brant le 25 avril, nous ne nous souvenons pas seulement d'un saint du pass\u00e9. Nous c\u00e9l\u00e9brons le fait que son \u0153uvre, inspir\u00e9e par l'Esprit Saint, se perp\u00e9tue. Le lion de saint Marc continue de rugir. Il continue d'\u00e9veiller les consciences, de r\u00e9conforter les malades, d'offrir de l'espoir aux d\u00e9sesp\u00e9r\u00e9s.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le d\u00e9fi que nous lance la f\u00eate de cet \u00e9vang\u00e9liste est double. D'une part, au niveau personnel, nous sommes appel\u00e9s \u00e0 red\u00e9couvrir son \u00c9vangile. Nous vous invitons aujourd'hui \u00e0 prendre votre Bible et \u00e0 lire, ne serait-ce que le premier chapitre de <strong>San Marcos<\/strong>. Prenez la r\u00e9solution d'accompagner J\u00e9sus, de vous laisser interpeller par son autorit\u00e9 et son amour compatissant.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">D'autre part, au niveau communautaire et eccl\u00e9sial, nous sommes appel\u00e9s \u00e0 soutenir la t\u00e2che d'\u00e9vang\u00e9lisation. Personne n'\u00e9vang\u00e9lise seul. Tout comme Marc a eu besoin de Barnab\u00e9, de Paul et de Pierre, nous sommes appel\u00e9s \u00e0 les soutenir. <a href=\"https:\/\/fundacioncarf.org\/historias\/\" target=\"_blank\" data-type=\"link\" data-id=\"https:\/\/fundacioncarf.org\/historias\/\" rel=\"noreferrer noopener\">les pr\u00eatres d'aujourd'hui<\/a> ils ont besoin de vous.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Votre soutien est le moteur de l'\u00c9vangile aujourd'hui<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le meilleur hommage que nous puissions rendre \u00e0 <strong>St Mark's<\/strong> le jour de sa f\u00eate est de faire en sorte que l'histoire de J\u00e9sus qu'il a \u00e9crite si fid\u00e8lement ne cesse jamais d'\u00eatre racont\u00e9e. Comment pouvez-vous faire en sorte que cela soit possible ? <a href=\"https:\/\/fundacioncarf.org\/sacerdocio\/vocacion-sacerdotal\/\" target=\"_blank\" data-type=\"link\" data-id=\"https:\/\/fundacioncarf.org\/sacerdocio\/vocacion-sacerdotal\/\" rel=\"noreferrer noopener\">Soutenir la formation de ceux qui consacrent leur vie \u00e0 la pr\u00e9dication de cette Parole<\/a>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A partir de la <strong>Fondation CARF<\/strong>, Nous vous encourageons \u00e0 rejoindre notre grande famille de partenaires, de bienfaiteurs et d'amis. <a href=\"https:\/\/fundacioncarf.org\/preguntas-frecuentes-habituales-fundacion-carf\/\" data-type=\"link\" data-id=\"https:\/\/fundacioncarf.org\/preguntas-frecuentes-habituales-fundacion-carf\/\" target=\"_blank\" rel=\"noreferrer noopener\">Chaque don<\/a>, L'argent, aussi petit soit-il, se transforme en heures d'\u00e9tude, en livres, en nourriture pour un s\u00e9minariste ou un pr\u00eatre qui, demain, c\u00e9l\u00e9brera l'Eucharistie et lira l'\u00c9vangile dans sa paroisse. <a href=\"https:\/\/fundacioncarf.org\/boletines-fundacion-carf\/\" data-type=\"link\" data-id=\"https:\/\/fundacioncarf.org\/boletines-fundacion-carf\/\" target=\"_blank\" rel=\"noreferrer noopener\">Parcourez notre site web<\/a> et d\u00e9couvrez comment votre g\u00e9n\u00e9rosit\u00e9 peut avoir un impact \u00e9ternel sur la formation des pasteurs de demain. Et suivez nos m\u00e9dias sociaux sur <code>@fundacioncarf<\/code> de rencontrer les visages de ceux que vous aidez \u00e0 se pr\u00e9parer \u00e0 \u00aballer dans le monde entier proclamer l'\u00c9vangile\u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Que Saint Marc interc\u00e8de pour l'Eglise, pour le Pape, pour tous les pr\u00eatres et religieux, et pour nous tous qui faisons partie du charisme promu par la Fondation CARF, afin que le grondement de la foi ne s'\u00e9teigne jamais dans nos c\u0153urs.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<div class=\"wp-block-rank-math-toc-block\" id=\"rank-math-toc\"><p><strong>Table des mati\u00e8res<\/strong><\/p><nav><ul><li class=\"\"><a href=\"#quien-fue-verdaderamente-san-marcos\">Qui \u00e9tait Saint Marc ?<\/a><\/li><li class=\"\"><a href=\"#el-evangelio-segun-san-marcos-caracteristicas-y-mensaje\">Quelles sont les caract\u00e9ristiques de l'\u00c9vangile selon Marc ?<\/a><ul><li class=\"\"><a href=\"#la-celebracion-del-25-de-abril-y-la-tradicion-eclesial\">C\u00e9l\u00e9bration du 25 avril et tradition <\/a><\/li><\/ul><\/li><\/ul><\/nav><\/div>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"T\u00c9MOINS : Histoires de pr\u00eatres\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/AI3Ibzei3_A?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>","protected":false},"excerpt":{"rendered":"<p>La f\u00eate de saint Marc, qui a lieu tous les 25 avril, nous invite \u00e0 red\u00e9couvrir le plus ancien \u00c9vangile de l'\u00c9glise. Dans cet article, nous explorons la vie de l'interpr\u00e8te de saint Pierre, la richesse spirituelle de son histoire et la pertinence de son mandat missionnaire. <\/p>","protected":false},"author":4,"featured_media":229273,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[13],"tags":[398,395,397,389,394],"class_list":["post-229271","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog","tag-apostoles","tag-evangelios","tag-palabra-de-dios","tag-sagrada-escritura","tag-san-marcos"],"acf":[],"_links":{"self":[{"href":"https:\/\/fundacioncarf.org\/fr\/wp-json\/wp\/v2\/posts\/229271","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fundacioncarf.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fundacioncarf.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fundacioncarf.org\/fr\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/fundacioncarf.org\/fr\/wp-json\/wp\/v2\/comments?post=229271"}],"version-history":[{"count":0,"href":"https:\/\/fundacioncarf.org\/fr\/wp-json\/wp\/v2\/posts\/229271\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fundacioncarf.org\/fr\/wp-json\/wp\/v2\/media\/229273"}],"wp:attachment":[{"href":"https:\/\/fundacioncarf.org\/fr\/wp-json\/wp\/v2\/media?parent=229271"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fundacioncarf.org\/fr\/wp-json\/wp\/v2\/categories?post=229271"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fundacioncarf.org\/fr\/wp-json\/wp\/v2\/tags?post=229271"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}